{"id":1498,"date":"2026-02-13T12:13:57","date_gmt":"2026-02-13T15:13:57","guid":{"rendered":"https:\/\/hospitalsanroque.gob.ar\/?p=1498"},"modified":"2026-02-13T12:51:13","modified_gmt":"2026-02-13T15:51:13","slug":"dia-mundial-de-las-cardiopatias-congenitas","status":"publish","type":"post","link":"https:\/\/hospitalsanroque.gob.ar\/index.php\/2026\/02\/13\/dia-mundial-de-las-cardiopatias-congenitas\/","title":{"rendered":"D\u00eda Mundial de las Cardiopat\u00edas Cong\u00e9nitas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1498\" class=\"elementor elementor-1498\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b60d645 e-flex e-con-boxed e-con e-parent\" data-id=\"b60d645\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-287cadf elementor-widget elementor-widget-heading\" data-id=\"287cadf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00eda Mundial de las Cardiopat\u00edas Cong\u00e9nitas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d46b65f elementor-widget elementor-widget-text-editor\" data-id=\"d46b65f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #666666; font-family: Roboto; font-size: 14px; text-align: center;\">Uno de los principales objetivos de la conmemoraci\u00f3n del D\u00eda Mundial de las Cardiopat\u00edas Cong\u00e9nitas es favorecer la detecci\u00f3n precoz (en la etapa prenatal y neonatal) y el acceso a un tratamiento oportuno a trav\u00e9s de la difusi\u00f3n de conocimiento sobre esta problem\u00e1tica.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ac1ed4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6ac1ed4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b36892 elementor-widget elementor-widget-image\" data-id=\"4b36892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"427\" src=\"https:\/\/hospitalsanroque.gob.ar\/wp-content\/uploads\/2026\/02\/cardiopatias-1024x427.jpg\" class=\"attachment-large size-large wp-image-1509\" alt=\"\" srcset=\"https:\/\/hospitalsanroque.gob.ar\/wp-content\/uploads\/2026\/02\/cardiopatias-1024x427.jpg 1024w, https:\/\/hospitalsanroque.gob.ar\/wp-content\/uploads\/2026\/02\/cardiopatias-300x125.jpg 300w, https:\/\/hospitalsanroque.gob.ar\/wp-content\/uploads\/2026\/02\/cardiopatias-768x320.jpg 768w, https:\/\/hospitalsanroque.gob.ar\/wp-content\/uploads\/2026\/02\/cardiopatias-1536x640.jpg 1536w, https:\/\/hospitalsanroque.gob.ar\/wp-content\/uploads\/2026\/02\/cardiopatias.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ceee647 elementor-widget elementor-widget-text-editor\" data-id=\"ceee647\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Uno de los principales objetivos de la conmemoraci\u00f3n del D\u00eda Mundial de las Cardiopat\u00edas Cong\u00e9nitas es<em><strong> favorecer la detecci\u00f3n precoz (en la etapa prenatal y neonatal) y el acceso a un tratamiento oportuno a trav\u00e9s de la difusi\u00f3n de conocimiento sobre esta problem\u00e1tica.<br \/><\/strong><\/em><\/p><p><span style=\"color: #808080;\"><em>El control durante el embarazo es important\u00edsimo ya que las cardiopat\u00edas se desarrollan y se pueden en etapas tempranas del embarazo.<\/em><\/span><\/p><p><br \/>Seg\u00fan datos del Ministerio De Salud de la Naci\u00f3n<em><strong> la cardiopat\u00eda cong\u00e9nita es la anomal\u00eda m\u00e1s com\u00fan y la primera causa de muerte en el primer a\u00f1o de vida.<\/strong><\/em><\/p><p>Se estima que uno de cada cien reci\u00e9n nacidos presenta alguna cardiopat\u00eda cong\u00e9nita.<\/p><p><em>En la Argentina, nacen al a\u00f1o unos 7 mil ni\u00f1os y ni\u00f1as con esta patolog\u00eda.<\/em><br \/><em>Alrededor del 50 por ciento de estos ni\u00f1os requieren cirug\u00eda en el primer a\u00f1o de vida y dos terceras partes son solucionables con diagn\u00f3stico oportuno y tratamiento.<\/em><\/p><h3>Pero, \u00bfqu\u00e9 es una cardiopat\u00eda cong\u00e9nita?<\/h3><p>\u00a0<\/p><p>La cardiopat\u00edas cong\u00e9nitas son problemas con la estructura y el funcionamiento del coraz\u00f3n (alteraciones en las paredes; v\u00e1lvulas o combinaciones de esto o de los grandes vasos sangu\u00edneos) que se puede encontrar en el feto y en el reci\u00e9n nacido.<\/p><p>Se forman en las primeras semanas de gestaci\u00f3n, se las padece desde el nacimiento y nunca se desarrollan luego de este.<\/p><p>Estas enfermedades pueden requerir soluci\u00f3n a muy temprana edad inclusive durante el embarazo mismo o en la edad adulta. Dicha soluci\u00f3n pasa desde simplemente medicaci\u00f3n, procedimientos llamados endovasculares donde no hace falta abrir el pecho o cirug\u00eda card\u00edaca.<\/p><h3>\u00bfC\u00f3mo se advierten las cardiopat\u00edas cong\u00e9nitas?<\/h3><p>El diagn\u00f3stico exacto se hace a trav\u00e9s del ecocardiograma (sumado al examen del m\u00e9dico y otros estudios como el electrocardiograma) y el tratamiento est\u00e1 a cargo del cardi\u00f3logo infantil.<\/p><p><em>En la mayor\u00eda de los casos la soluci\u00f3n es favorable salvo casos complejos.<\/em><\/p><p>Ante la sospecha de estas enfermedades debe consultar a su pediatra y este guiar\u00e1 el estudio.<br \/><br \/>Otras cuestiones a tener en cuenta<br \/>Se habla de 2 tipos de afecciones card\u00edacas cong\u00e9nitas:<\/p><ul><li>cian\u00f3tica<\/li><li>no cian\u00f3tica<\/li><\/ul><p>Una condici\u00f3n cian\u00f3tica hace que los labios, enc\u00edas, u\u00f1as y la piel se tornen de color azul, a causa de la insuficiencia de ox\u00edgeno en la sangre.<\/p><p>Muchos ni\u00f1os con un defecto card\u00edaco cong\u00e9nito presentan s\u00edntomas que llaman mucho la atenci\u00f3n a los padres y cuidadores como:<\/p><ul><li>Respiraci\u00f3n m\u00e1s r\u00e1pida de lo habitual en forma permanente.<\/li><li>Color azuloso o morado de labios, u\u00f1as, piel.<\/li><li>Hospitalizaciones frecuentes por infecci\u00f3n respiratoria (neumon\u00eda).<\/li><li>Poca ganancia de peso y de talla.<\/li><li>Desmayos (s\u00edncope) a cualquier edad.<\/li><li>Antecedente de muerte s\u00fabita no explicada en familiares menores de 50 a\u00f1os.<\/li><li>Historia familiar de soplos cardiacos o enfermedad cong\u00e9nita en el coraz\u00f3n.<\/li><li>Fatiga, cansancio, sudoraci\u00f3n profusa en la edad de la lactancia (menores de 2 a\u00f1os).<\/li><li>El m\u00e9dico encuentre un soplo en el coraz\u00f3n.<\/li><li>La presencia de uno de estos s\u00edntomas o antecedentes amerita una revisi\u00f3n m\u00e9dica del ni\u00f1o por pediatr\u00eda, y si el caso lo amerita, por el cardi\u00f3logo pediatra.<\/li><\/ul><p>Muchos defectos cardi\u00e1cos pueden manejarse exitosamente, el tratamiento depende de la parte afectada, algunos ni\u00f1os no necesitan tratamiento, mientras que otros requieren tratamiento m\u00e9dico, cateterismo cardiaco y\/o cirug\u00eda cardiaca. Algunos defectos son tratados por pasos, otros se tratan posteriormente. Algunos defectos cardiacos cong\u00e9nitos no son curables, se puede vivir con ellos, teniendo un buen acompa\u00f1amiento familiar, medico, nutricional y social.<\/p><p>Lo m\u00e1s importante, es estar atentos a los signos y s\u00edntomas, para tener un diagn\u00f3stico temprano y darle al paciente el tratamiento necesario para mejorar su salud.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u00eda Mundial de las Cardiopat\u00edas Cong\u00e9nitas Uno de los principales objetivos de la conmemoraci\u00f3n del D\u00eda Mundial de las Cardiopat\u00edas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-1498","post","type-post","status-publish","format-standard","hentry","category-noticias","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=1498"}],"version-history":[{"count":11,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1498\/revisions"}],"predecessor-version":[{"id":1512,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1498\/revisions\/1512"}],"wp:attachment":[{"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=1498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=1498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=1498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}