{"id":1952,"date":"2024-10-04T10:34:53","date_gmt":"2024-10-04T13:34:53","guid":{"rendered":"https:\/\/hospitalsanroque.gob.ar\/?p=1952"},"modified":"2026-04-14T10:36:30","modified_gmt":"2026-04-14T13:36:30","slug":"mejoras-organizacionales-en-consultorios-externos-de-obstetricia-y-ecografia","status":"publish","type":"post","link":"https:\/\/hospitalsanroque.gob.ar\/index.php\/2024\/10\/04\/mejoras-organizacionales-en-consultorios-externos-de-obstetricia-y-ecografia\/","title":{"rendered":"Mejoras organizacionales en Consultorios Externos de Obstetricia y Ecograf\u00eda"},"content":{"rendered":"\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Durante las \u00faltimas semanas, nuestro hospital ha realizados mejoras funcionales en la administraci\u00f3n de los Consultorios Externos de Obtetricia.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Estas mejora es parte de una estrategia institucional para lograr&nbsp;<strong>mayor accesibilidad<\/strong>, un&nbsp;<strong>fortalecimiento del&nbsp; trabajo en red<\/strong>&nbsp;con los dem\u00e1s efectores provinciales,<strong>&nbsp;la implementaci\u00f3n de la gesti\u00f3n digitalizada de turnos y de la de historia cl\u00ednica electr\u00f3nic<\/strong>a.<\/p>\n<\/blockquote>\n\n\n\n<p>De esta manera se consolida un paso en el camino trazado por la circular N\u00b01 del Programa Entrerriano de Salud, que busca potenciar la accesibilidad de la atenci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cambios<\/strong><\/h3>\n\n\n\n<p>Desde el principio del mes pasado, la Secretar\u00eda y la&nbsp; gesti\u00f3n administrativa de los consultorios externos del Servicio de Obstetricia y de Ecograf\u00eda pasaron a estar a cargo de la&nbsp;<a href=\"https:\/\/historico.hospitalsanroque.gob.ar\/seccion\/articulos\/389\/gestion-integral-en-red#:~:text=Contacto,red@hospitalsanroque.gob.ar\">Divisi\u00f3n de Gesti\u00f3n Integral en Red<\/a>&nbsp;(antes Referencia y CR).&nbsp; El personal administrativo es el mismo, pero a trav\u00e9s del cambio organizacional se va consolidando una forma de trabajo centrada en la mejora del servicio y la productividad.&nbsp;<\/p>\n\n\n\n<p>Para lograr ambientes de mayor privacidad a la hora de consultar o pedir orientaci\u00f3n, se hicieron modificaciones en la disposici\u00f3n e infraestructura de la Secretar\u00eda de Consultorios Externos de Obstetricia.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Adem\u00e1s, personal de Gesti\u00f3n en Red acompa\u00f1a a los profesionales en la estrategia de implementaci\u00f3n de la HEC y el uso de la turnera SADER. Tambi\u00e9n se optimiza el recurso profesional ya que se hace un mejor monitoreo de la actividad.<\/p>\n<\/blockquote>\n\n\n\n<p>Es destacable que estos cambios se han ido facilitando gracias a la predisposici\u00f3n del personal de obstetricia. Durante este proceso han mostrado intereses y compromiso con los y las nuevas estrategias digitales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 cambia para los pacientes?<\/strong><\/h3>\n\n\n\n<p>Se apuesta a lograr una mayor&nbsp;<strong>accesibilidad y una mejor orientaci\u00f3n de las pacientes<\/strong>&nbsp;y sus familias. Por ello,<em>&nbsp;los pedidos de atenci\u00f3n programada se hacen desde los Centros de Salud<\/em>, aunque, respetando el principio de captaci\u00f3n oportuna, se seguir\u00e1n asignando turnos de manera telef\u00f3nica y presencial. Se contrarreferencia a las pacientes en los lugares de atenci\u00f3n que sean m\u00e1s convenientes y se le da un seguimiento administrativo al curso de su proceso de atenci\u00f3n. La&nbsp;<strong>Historia Cl\u00ednica Electr\u00f3nica<\/strong>&nbsp;desarrollada por<strong>&nbsp;Salud Digital de Entre R\u00edos<\/strong>, es la herramienta clave para poner en funcionamiento la red, ya que es transversal a todo el sistema de salud y consultable desde todos los efectores de la provincia.<\/p>\n\n\n\n<p>Finalmente, al optimizar el recurso humano profesional, aumenta la capacidad de atenci\u00f3n y disminuyen las cancelaciones y reprogramaciones. La formalizaci\u00f3n de la gesti\u00f3n de los turnos de efector a efector, ayuda a identificar y corregir fallas en la articulaci\u00f3n del sistema y a atender las demandas de la mejor manera.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>En lo que va de estas 6 semanas de este cambio institucional,<strong>&nbsp;todos los consultorios externos de obstetricia han activado sus turneras y todos los profesionales ( obst\u00e9tricas, m\u00e9dicos y enfermeras) est\u00e1n haciendo el registro de las atenciones en la Historia Cl\u00ednica Electr\u00f3nica de SADER.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La estrategia SADER y la Gesti\u00f3n Integral en Red en el hospital<\/strong><\/h3>\n\n\n\n<p>Adem\u00e1s de ser un hospital de alta complejidad, somos parte de un Sistema de Salud que debe&nbsp;<strong>dar respuestas de manera integrada utilizando las herramientas desarrolladas por Salud Digital de Entre R\u00edos (SaDER)<\/strong><\/p>\n\n\n\n<p>En nuestro hospital, desde enero a la fecha, llevamos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>37000 turnos otorgados<\/li>\n\n\n\n<li>3900 registros en HCE<\/li>\n\n\n\n<li>35 Servicios de Consultorios Externos ya tienen turneras habilitadas<\/li>\n\n\n\n<li>33 de los 34 servicios de atenci\u00f3n ambulatoria ya est\u00e1n trabajando con la turnera SADER y trabajan con la Historia Cl\u00ednica Electr\u00f3nica<\/li>\n\n\n\n<li>438 profesionales registrados<\/li>\n\n\n\n<li>216 turneras creadas<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Durante las \u00faltimas semanas, nuestro hospital ha realizados mejoras funcionales en la administraci\u00f3n de los Consultorios Externos de Obtetricia. Estas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1952","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=1952"}],"version-history":[{"count":1,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1952\/revisions"}],"predecessor-version":[{"id":1953,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/1952\/revisions\/1953"}],"wp:attachment":[{"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=1952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=1952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hospitalsanroque.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=1952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}